{"id":578,"date":"2019-04-11T11:49:28","date_gmt":"2019-04-11T17:49:28","guid":{"rendered":"http:\/\/westenddiversresort.com\/habitaciones\/"},"modified":"2025-09-09T17:13:57","modified_gmt":"2025-09-09T23:13:57","slug":"habitaciones","status":"publish","type":"page","link":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/","title":{"rendered":"Habitaciones"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.1&#8243; custom_padding=\u00bb40px|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dsm_card title=\u00bbHABITACION ESTANDARD\u00bb subtitle=\u00bb1 Cama Doble &#8211; Max. 2 personas\u00bb content_equal_height=\u00bbon\u00bb image=\u00bbhttps:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2022\/11\/west-end-dive-resort-room-2022.jpg\u00bb badge_text=\u00bbdesde $69&#8243; badge_background_color=\u00bb#d37e00&#8243; content_padding=\u00bb20px|16px|20px|16px|false|true\u00bb button_text=\u00bbM\u00e1s Detalles\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMzMSJ9fQ==@\u00bb button_url_new_window=\u00bb1&#8243; layout_tablet=\u00bb\u00bb layout_phone=\u00bbstacked\u00bb layout_last_edited=\u00bbon|phone\u00bb content_padding_tablet=\u00bb\u00bb content_padding_phone=\u00bb\u00bb content_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb badge_font=\u00bb|600|||||||\u00bb badge_text_color=\u00bb#FFFFFF\u00bb badge_font_size=\u00bb14px\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb28px\u00bb header_line_height=\u00bb0.8em\u00bb body_font_size=\u00bb18px\u00bb subhead_font=\u00bb|600|||||||\u00bb subhead_line_height=\u00bb2.2em\u00bb background_color=\u00bbrgba(239,239,239,0.68)\u00bb background_enable_pattern_style=\u00bbon\u00bb background_pattern_style=\u00bbwaves\u00bb background_pattern_color=\u00bb#f7f7f7&#8243; background_pattern_size=\u00bbcustom\u00bb background_pattern_width=\u00bb58px\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#3f3f3f\u00bb button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#0C71C3&#8243; button_border_radius=\u00bb6px\u00bb button_font=\u00bb||||||||\u00bb button_alignment=\u00bbright\u00bb border_radii=\u00bbon|11px|11px|11px|11px\u00bb box_shadow_style_button=\u00bbpreset3&#8243; box_shadow_color_button=\u00bbrgba(0,0,0,0.18)\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><span>Aire Acondicionado, Ventilador de Techo, TV Cable, WiFi y Vista a la Piscina.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dsm_card title=\u00bbSUITE\u00bb subtitle=\u00bb1 Dormitorio &#8211; Max. 2 personas\u00bb content_equal_height=\u00bbon\u00bb image=\u00bbhttps:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2025\/09\/west-end-dive-resort-suite-room-window.jpg\u00bb badge_text=\u00bbSuite\u00bb badge_background_color=\u00bb#d37e00&#8243; alt=\u00bbWest End Dive Resort Ssunset Villas vista desde el drone\u00bb content_padding=\u00bb20px|16px|20px|16px|false|true\u00bb button_text=\u00bbM\u00e1s Detalles\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE0MDMifX0=@\u00bb button_url_new_window=\u00bb1&#8243; layout_tablet=\u00bb\u00bb layout_phone=\u00bbstacked\u00bb layout_last_edited=\u00bbon|phone\u00bb content_padding_tablet=\u00bb\u00bb content_padding_phone=\u00bb\u00bb content_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb badge_font=\u00bb|600|||||||\u00bb badge_text_color=\u00bb#FFFFFF\u00bb badge_font_size=\u00bb14px\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb28px\u00bb header_line_height=\u00bb0.8em\u00bb body_font_size=\u00bb18px\u00bb subhead_font=\u00bb|600|||||||\u00bb subhead_line_height=\u00bb2.2em\u00bb background_color=\u00bbrgba(239,239,239,0.68)\u00bb background_enable_pattern_style=\u00bbon\u00bb background_pattern_style=\u00bbwaves\u00bb background_pattern_color=\u00bb#f7f7f7&#8243; background_pattern_size=\u00bbcustom\u00bb background_pattern_width=\u00bb58px\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#3f3f3f\u00bb button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#0C71C3&#8243; button_border_radius=\u00bb6px\u00bb button_font=\u00bb||||||||\u00bb button_alignment=\u00bbright\u00bb hover_enabled=\u00bb0&#8243; border_radii=\u00bbon|11px|11px|11px|11px\u00bb box_shadow_style_button=\u00bbpreset3&#8243; box_shadow_color_button=\u00bbrgba(0,0,0,0.18)\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><span>Aire acondicionado, C\u00f3moda cama King size, TV por cable, wifi gratuito y cocineta.<\/span><\/p>\n<p>[\/dsm_card][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.19.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dsm_card title=\u00bbSUNSET VILLAS\u00bb subtitle=\u00bb2 Dormitorios \/ 2 Ba\u00f1os &#8211; Max. 6 personas\u00bb content_equal_height=\u00bbon\u00bb image=\u00bbhttps:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2024\/07\/west-end-dive-resort-sunset-villas-drone-view.jpg\u00bb badge_text=\u00bbSunset Villas\u00bb badge_background_color=\u00bb#d37e00&#8243; alt=\u00bbWest End Dive Resort Ssunset Villas vista desde el drone\u00bb content_padding=\u00bb20px|16px|20px|16px|false|true\u00bb button_text=\u00bbM\u00e1s Detalles\u00bb button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjEzMzUifX0=@\u00bb button_url_new_window=\u00bb1&#8243; layout_tablet=\u00bb\u00bb layout_phone=\u00bbstacked\u00bb layout_last_edited=\u00bbon|phone\u00bb content_padding_tablet=\u00bb\u00bb content_padding_phone=\u00bb\u00bb content_padding_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb badge_font=\u00bb|600|||||||\u00bb badge_text_color=\u00bb#FFFFFF\u00bb badge_font_size=\u00bb14px\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb28px\u00bb header_line_height=\u00bb0.8em\u00bb body_font_size=\u00bb18px\u00bb subhead_font=\u00bb|600|||||||\u00bb subhead_line_height=\u00bb2.2em\u00bb background_color=\u00bbrgba(239,239,239,0.68)\u00bb background_enable_pattern_style=\u00bbon\u00bb background_pattern_style=\u00bbwaves\u00bb background_pattern_color=\u00bb#f7f7f7&#8243; background_pattern_size=\u00bbcustom\u00bb background_pattern_width=\u00bb58px\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#3f3f3f\u00bb button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#0C71C3&#8243; button_border_radius=\u00bb6px\u00bb button_font=\u00bb||||||||\u00bb button_alignment=\u00bbright\u00bb border_radii=\u00bbon|11px|11px|11px|11px\u00bb box_shadow_style_button=\u00bbpreset3&#8243; box_shadow_color_button=\u00bbrgba(0,0,0,0.18)\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Aire Acondicionado, TV Cable, Wifi y Ventiladores de Techo.<\/p>\n<p>[\/dsm_card][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_card dsm_card_0 et_pb_bg_layout_light  dsm_card_layout_stacked\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_background_pattern\"><\/span>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t\n\t\t\t\n\t\t\t<figure class=\"dsm_card_image_wrapper dsm_card_badge_top_right\"><div class=\"dsm_card_image_background dsm_card_img\"><\/div><div class=\"dsm_card_badge_text\">desde $69<\/div><\/figure>\n\t\t\t<div class=\"et_pb_module dsm_card_wrapper et_pb_text_align_left\">\n\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"dsm_card_title et_pb_module_header\">HABITACION ESTANDARD<\/h4>\n\t\t\t\t\t<div class=\"dsm_card_subtitle\">1 Cama Doble - Max. 2 personas<\/div>\n\t\t\t\t\t<div class=\"dsm_card_description\">Aire Acondicionado, Ventilador de Techo, TV Cable, WiFi y Vista a la Piscina.<\/div>\n\t\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_more_button \" href=\"\">M\u00e1s Detalles<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module dsm_card dsm_card_1 et_pb_bg_layout_light  dsm_card_layout_stacked\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_background_pattern\"><\/span>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t\n\t\t\t\n\t\t\t<figure class=\"dsm_card_image_wrapper dsm_card_badge_top_right\"><div class=\"dsm_card_image_background dsm_card_img\"><\/div><div class=\"dsm_card_badge_text\">Suite<\/div><\/figure>\n\t\t\t<div class=\"et_pb_module dsm_card_wrapper et_pb_text_align_left\">\n\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"dsm_card_title et_pb_module_header\">SUITE<\/h4>\n\t\t\t\t\t<div class=\"dsm_card_subtitle\">1 Dormitorio - Max. 2 personas<\/div>\n\t\t\t\t\t<div class=\"dsm_card_description\">Aire acondicionado, C\u00f3moda cama King size, TV por cable, wifi gratuito y cocineta.<\/div>\n\t\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_more_button \" href=\"\">M\u00e1s Detalles<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module dsm_card dsm_card_2 et_pb_bg_layout_light  dsm_card_layout_stacked\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_background_pattern\"><\/span>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t\n\t\t\t\n\t\t\t<figure class=\"dsm_card_image_wrapper dsm_card_badge_top_right\"><div class=\"dsm_card_image_background dsm_card_img\"><\/div><div class=\"dsm_card_badge_text\">\u00bbSunset<\/div><\/figure>\n\t\t\t<div class=\"et_pb_module dsm_card_wrapper et_pb_text_align_left\">\n\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"dsm_card_title et_pb_module_header\">\u00bbSUNSET<\/h4>\n\t\t\t\t\t<div class=\"dsm_card_subtitle\">\u00bb2<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_more_button \" href=\"http:\/\/\u00bb\u00bb\">\u00bbM\u00e1s<\/a><\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-578","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Habitaciones - West End Dive Resort<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habitaciones - West End Dive Resort\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"West End Dive Resort\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-09T23:13:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"[dsm_card title=&quot;HABITACION ESTANDARD&quot; subtitle=&quot;1 Cama Doble - Max. 2 personas&quot; content_equal_height=&quot;on&quot; image=&quot;https:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2022\/11\/west-end-dive-resort-room-2022.jpg&quot; badge_text=&quot;desde $69&quot; badge_background_color=&quot;#d37e00&quot; content_padding=&quot;20px|16px|20px|16px|false|true&quot; button_text=&quot;M\u00e1s Detalles&quot; button_url=&quot;&quot; button_url_new_window=&quot;1&quot; layout_tablet=&quot;&quot; layout_phone=&quot;stacked&quot; layout_last_edited=&quot;on|phone&quot; content_padding_tablet=&quot;&quot; content_padding_phone=&quot;&quot; content_padding_last_edited=&quot;on|desktop&quot; _builder_version=&quot;4.27.4&quot; _dynamic_attributes=&quot;button_url&quot; _module_preset=&quot;default&quot; badge_font=&quot;|600|||||||&quot; badge_text_color=&quot;#FFFFFF&quot; badge_font_size=&quot;14px&quot; header_font=&quot;|700|||||||&quot; header_font_size=&quot;28px&quot; header_line_height=&quot;0.8em&quot; body_font_size=&quot;18px&quot; subhead_font=&quot;|600|||||||&quot; subhead_line_height=&quot;2.2em&quot; background_color=&quot;rgba(239,239,239,0.68)&quot; background_enable_pattern_style=&quot;on&quot; background_pattern_style=&quot;waves&quot; background_pattern_color=&quot;#f7f7f7&quot; background_pattern_size=&quot;custom&quot; background_pattern_width=&quot;58px&quot; custom_button=&quot;on&quot; button_text_size=&quot;18px&quot; button_text_color=&quot;#3f3f3f&quot; button_bg_color=&quot;#FFFFFF&quot; button_border_width=&quot;0px&quot; button_border_color=&quot;#0C71C3&quot; button_border_radius=&quot;6px&quot; button_font=&quot;||||||||&quot; button_alignment=&quot;right&quot; border_radii=&quot;on|11px|11px|11px|11px&quot; box_shadow_style_button=&quot;preset3&quot; box_shadow_color_button=&quot;rgba(0,0,0,0.18)&quot; global_colors_info=&quot;{}&quot; theme_builder_area=&quot;post_content&quot;]Aire Acondicionado, Ventilador de Techo, TV Cable, WiFi y Vista a la Piscina.[\/dsm_card][dsm_card title=&quot;SUITE&quot; subtitle=&quot;1 Dormitorio - Max. 2 personas&quot; content_equal_height=&quot;on&quot; image=&quot;https:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2025\/09\/west-end-dive-resort-suite-room-window.jpg&quot; badge_text=&quot;Suite&quot; badge_background_color=&quot;#d37e00&quot; alt=&quot;West End Dive Resort Ssunset Villas vista desde el drone&quot; content_padding=&quot;20px|16px|20px|16px|false|true&quot; button_text=&quot;M\u00e1s Detalles&quot; button_url=&quot;&quot; button_url_new_window=&quot;1&quot; layout_tablet=&quot;&quot; layout_phone=&quot;stacked&quot; layout_last_edited=&quot;on|phone&quot; content_padding_tablet=&quot;&quot; content_padding_phone=&quot;&quot; content_padding_last_edited=&quot;on|desktop&quot; _builder_version=&quot;4.27.4&quot; _dynamic_attributes=&quot;button_url&quot; _module_preset=&quot;default&quot; badge_font=&quot;|600|||||||&quot; badge_text_color=&quot;#FFFFFF&quot; badge_font_size=&quot;14px&quot; header_font=&quot;|700|||||||&quot; header_font_size=&quot;28px&quot; header_line_height=&quot;0.8em&quot; body_font_size=&quot;18px&quot; subhead_font=&quot;|600|||||||&quot; subhead_line_height=&quot;2.2em&quot; background_color=&quot;rgba(239,239,239,0.68)&quot; background_enable_pattern_style=&quot;on&quot; background_pattern_style=&quot;waves&quot; background_pattern_color=&quot;#f7f7f7&quot; background_pattern_size=&quot;custom&quot; background_pattern_width=&quot;58px&quot; custom_button=&quot;on&quot; button_text_size=&quot;18px&quot; button_text_color=&quot;#3f3f3f&quot; button_bg_color=&quot;#FFFFFF&quot; button_border_width=&quot;0px&quot; button_border_color=&quot;#0C71C3&quot; button_border_radius=&quot;6px&quot; button_font=&quot;||||||||&quot; button_alignment=&quot;right&quot; hover_enabled=&quot;0&quot; border_radii=&quot;on|11px|11px|11px|11px&quot; box_shadow_style_button=&quot;preset3&quot; box_shadow_color_button=&quot;rgba(0,0,0,0.18)&quot; global_colors_info=&quot;{}&quot; theme_builder_area=&quot;post_content&quot; sticky_enabled=&quot;0&quot;]Aire acondicionado, C\u00f3moda cama King size, TV por cable, wifi gratuito y cocineta.[\/dsm_card][dsm_card title=&quot;SUNSET VILLAS&quot; subtitle=&quot;2 Dormitorios \/ 2 Ba\u00f1os - Max. 6 personas&quot; content_equal_height=&quot;on&quot; image=&quot;https:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2024\/07\/west-end-dive-resort-sunset-villas-drone-view.jpg&quot; badge_text=&quot;Sunset Villas&quot; badge_background_color=&quot;#d37e00&quot; alt=&quot;West End Dive Resort Ssunset Villas vista desde el drone&quot; content_padding=&quot;20px|16px|20px|16px|false|true&quot; button_text=&quot;M\u00e1s Detalles&quot; button_url=&quot;&quot; button_url_new_window=&quot;1&quot; layout_tablet=&quot;&quot; layout_phone=&quot;stacked&quot; layout_last_edited=&quot;on|phone&quot; content_padding_tablet=&quot;&quot; content_padding_phone=&quot;&quot; content_padding_last_edited=&quot;on|desktop&quot; _builder_version=&quot;4.27.4&quot; _dynamic_attributes=&quot;button_url&quot; _module_preset=&quot;default&quot; badge_font=&quot;|600|||||||&quot; badge_text_color=&quot;#FFFFFF&quot; badge_font_size=&quot;14px&quot; header_font=&quot;|700|||||||&quot; header_font_size=&quot;28px&quot; header_line_height=&quot;0.8em&quot; body_font_size=&quot;18px&quot; subhead_font=&quot;|600|||||||&quot; subhead_line_height=&quot;2.2em&quot; background_color=&quot;rgba(239,239,239,0.68)&quot; background_enable_pattern_style=&quot;on&quot; background_pattern_style=&quot;waves&quot; [&hellip;]\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/habitaciones\\\/\",\"url\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/habitaciones\\\/\",\"name\":\"Habitaciones - West End Dive Resort\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/#website\"},\"datePublished\":\"2019-04-11T17:49:28+00:00\",\"dateModified\":\"2025-09-09T23:13:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/habitaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/habitaciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/habitaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habitaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/\",\"name\":\"West End Dive Resort\",\"description\":\"Roatan, Bay Islands, Honduras\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/roatanwestenddiveresort.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Habitaciones - West End Dive Resort","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/","og_locale":"es_ES","og_type":"article","og_title":"Habitaciones - West End Dive Resort","og_url":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/","og_site_name":"West End Dive Resort","article_modified_time":"2025-09-09T23:13:57+00:00","twitter_card":"summary_large_image","twitter_description":"[dsm_card title=\"HABITACION ESTANDARD\" subtitle=\"1 Cama Doble - Max. 2 personas\" content_equal_height=\"on\" image=\"https:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2022\/11\/west-end-dive-resort-room-2022.jpg\" badge_text=\"desde $69\" badge_background_color=\"#d37e00\" content_padding=\"20px|16px|20px|16px|false|true\" button_text=\"M\u00e1s Detalles\" button_url=\"\" button_url_new_window=\"1\" layout_tablet=\"\" layout_phone=\"stacked\" layout_last_edited=\"on|phone\" content_padding_tablet=\"\" content_padding_phone=\"\" content_padding_last_edited=\"on|desktop\" _builder_version=\"4.27.4\" _dynamic_attributes=\"button_url\" _module_preset=\"default\" badge_font=\"|600|||||||\" badge_text_color=\"#FFFFFF\" badge_font_size=\"14px\" header_font=\"|700|||||||\" header_font_size=\"28px\" header_line_height=\"0.8em\" body_font_size=\"18px\" subhead_font=\"|600|||||||\" subhead_line_height=\"2.2em\" background_color=\"rgba(239,239,239,0.68)\" background_enable_pattern_style=\"on\" background_pattern_style=\"waves\" background_pattern_color=\"#f7f7f7\" background_pattern_size=\"custom\" background_pattern_width=\"58px\" custom_button=\"on\" button_text_size=\"18px\" button_text_color=\"#3f3f3f\" button_bg_color=\"#FFFFFF\" button_border_width=\"0px\" button_border_color=\"#0C71C3\" button_border_radius=\"6px\" button_font=\"||||||||\" button_alignment=\"right\" border_radii=\"on|11px|11px|11px|11px\" box_shadow_style_button=\"preset3\" box_shadow_color_button=\"rgba(0,0,0,0.18)\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"]Aire Acondicionado, Ventilador de Techo, TV Cable, WiFi y Vista a la Piscina.[\/dsm_card][dsm_card title=\"SUITE\" subtitle=\"1 Dormitorio - Max. 2 personas\" content_equal_height=\"on\" image=\"https:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2025\/09\/west-end-dive-resort-suite-room-window.jpg\" badge_text=\"Suite\" badge_background_color=\"#d37e00\" alt=\"West End Dive Resort Ssunset Villas vista desde el drone\" content_padding=\"20px|16px|20px|16px|false|true\" button_text=\"M\u00e1s Detalles\" button_url=\"\" button_url_new_window=\"1\" layout_tablet=\"\" layout_phone=\"stacked\" layout_last_edited=\"on|phone\" content_padding_tablet=\"\" content_padding_phone=\"\" content_padding_last_edited=\"on|desktop\" _builder_version=\"4.27.4\" _dynamic_attributes=\"button_url\" _module_preset=\"default\" badge_font=\"|600|||||||\" badge_text_color=\"#FFFFFF\" badge_font_size=\"14px\" header_font=\"|700|||||||\" header_font_size=\"28px\" header_line_height=\"0.8em\" body_font_size=\"18px\" subhead_font=\"|600|||||||\" subhead_line_height=\"2.2em\" background_color=\"rgba(239,239,239,0.68)\" background_enable_pattern_style=\"on\" background_pattern_style=\"waves\" background_pattern_color=\"#f7f7f7\" background_pattern_size=\"custom\" background_pattern_width=\"58px\" custom_button=\"on\" button_text_size=\"18px\" button_text_color=\"#3f3f3f\" button_bg_color=\"#FFFFFF\" button_border_width=\"0px\" button_border_color=\"#0C71C3\" button_border_radius=\"6px\" button_font=\"||||||||\" button_alignment=\"right\" hover_enabled=\"0\" border_radii=\"on|11px|11px|11px|11px\" box_shadow_style_button=\"preset3\" box_shadow_color_button=\"rgba(0,0,0,0.18)\" global_colors_info=\"{}\" theme_builder_area=\"post_content\" sticky_enabled=\"0\"]Aire acondicionado, C\u00f3moda cama King size, TV por cable, wifi gratuito y cocineta.[\/dsm_card][dsm_card title=\"SUNSET VILLAS\" subtitle=\"2 Dormitorios \/ 2 Ba\u00f1os - Max. 6 personas\" content_equal_height=\"on\" image=\"https:\/\/roatanwestenddiveresort.com\/wp-content\/uploads\/2024\/07\/west-end-dive-resort-sunset-villas-drone-view.jpg\" badge_text=\"Sunset Villas\" badge_background_color=\"#d37e00\" alt=\"West End Dive Resort Ssunset Villas vista desde el drone\" content_padding=\"20px|16px|20px|16px|false|true\" button_text=\"M\u00e1s Detalles\" button_url=\"\" button_url_new_window=\"1\" layout_tablet=\"\" layout_phone=\"stacked\" layout_last_edited=\"on|phone\" content_padding_tablet=\"\" content_padding_phone=\"\" content_padding_last_edited=\"on|desktop\" _builder_version=\"4.27.4\" _dynamic_attributes=\"button_url\" _module_preset=\"default\" badge_font=\"|600|||||||\" badge_text_color=\"#FFFFFF\" badge_font_size=\"14px\" header_font=\"|700|||||||\" header_font_size=\"28px\" header_line_height=\"0.8em\" body_font_size=\"18px\" subhead_font=\"|600|||||||\" subhead_line_height=\"2.2em\" background_color=\"rgba(239,239,239,0.68)\" background_enable_pattern_style=\"on\" background_pattern_style=\"waves\" [&hellip;]","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/","url":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/","name":"Habitaciones - West End Dive Resort","isPartOf":{"@id":"https:\/\/roatanwestenddiveresort.com\/es\/#website"},"datePublished":"2019-04-11T17:49:28+00:00","dateModified":"2025-09-09T23:13:57+00:00","breadcrumb":{"@id":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/roatanwestenddiveresort.com\/es\/habitaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/roatanwestenddiveresort.com\/es\/"},{"@type":"ListItem","position":2,"name":"Habitaciones"}]},{"@type":"WebSite","@id":"https:\/\/roatanwestenddiveresort.com\/es\/#website","url":"https:\/\/roatanwestenddiveresort.com\/es\/","name":"West End Dive Resort","description":"Roatan, Bay Islands, Honduras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roatanwestenddiveresort.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/pages\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":53,"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/pages\/578\/revisions"}],"predecessor-version":[{"id":1458,"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/pages\/578\/revisions\/1458"}],"wp:attachment":[{"href":"https:\/\/roatanwestenddiveresort.com\/es\/wp-json\/wp\/v2\/media?parent=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}